{"id":36,"date":"2021-02-17T19:20:23","date_gmt":"2021-02-17T19:20:23","guid":{"rendered":"https:\/\/www.ceipmestalla.com\/?page_id=36"},"modified":"2022-04-01T14:36:02","modified_gmt":"2022-04-01T12:36:02","slug":"equipo-docente","status":"publish","type":"page","link":"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/","title":{"rendered":"Equipo Docente"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/clics.gif\" alt=\"\" class=\"wp-image-212\" width=\"1117\" height=\"313\"\/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center has-text-color has-background\" style=\"background-color:#42628f;color:#f8f8f8;font-size:32px\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-36","page","type-page","status-publish","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Equipo Docente - Ceip Mestalla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equipo Docente - Ceip Mestalla\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/\" \/>\n<meta property=\"og:site_name\" content=\"Ceip Mestalla\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-01T12:36:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/clics.gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@emestalla\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/\",\"url\":\"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/\",\"name\":\"Equipo Docente - Ceip Mestalla\",\"isPartOf\":{\"@id\":\"https:\/\/www.ceipmestalla.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/clics.gif\",\"datePublished\":\"2021-02-17T19:20:23+00:00\",\"dateModified\":\"2022-04-01T12:36:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/#primaryimage\",\"url\":\"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/clics.gif\",\"contentUrl\":\"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/clics.gif\",\"width\":701,\"height\":196},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.ceipmestalla.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equipo Docente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ceipmestalla.com\/#website\",\"url\":\"https:\/\/www.ceipmestalla.com\/\",\"name\":\"Ceip Mestalla\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ceipmestalla.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ceipmestalla.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ceipmestalla.com\/#organization\",\"name\":\"Ceip Mestalla\",\"url\":\"https:\/\/www.ceipmestalla.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ceipmestalla.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/cropped-cropped-cropped-cropped-LOGO_Mestalla-1-e1614470494422.png\",\"contentUrl\":\"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/cropped-cropped-cropped-cropped-LOGO_Mestalla-1-e1614470494422.png\",\"width\":500,\"height\":191,\"caption\":\"Ceip Mestalla\"},\"image\":{\"@id\":\"https:\/\/www.ceipmestalla.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/emestalla\",\"https:\/\/www.instagram.com\/colegiomestalla\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equipo Docente - Ceip Mestalla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/","og_locale":"es_ES","og_type":"article","og_title":"Equipo Docente - Ceip Mestalla","og_url":"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/","og_site_name":"Ceip Mestalla","article_modified_time":"2022-04-01T12:36:02+00:00","og_image":[{"url":"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/clics.gif","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@emestalla","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/","url":"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/","name":"Equipo Docente - Ceip Mestalla","isPartOf":{"@id":"https:\/\/www.ceipmestalla.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/#primaryimage"},"image":{"@id":"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/clics.gif","datePublished":"2021-02-17T19:20:23+00:00","dateModified":"2022-04-01T12:36:02+00:00","breadcrumb":{"@id":"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/#primaryimage","url":"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/clics.gif","contentUrl":"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/clics.gif","width":701,"height":196},{"@type":"BreadcrumbList","@id":"https:\/\/www.ceipmestalla.com\/index.php\/equipo-docente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ceipmestalla.com\/"},{"@type":"ListItem","position":2,"name":"Equipo Docente"}]},{"@type":"WebSite","@id":"https:\/\/www.ceipmestalla.com\/#website","url":"https:\/\/www.ceipmestalla.com\/","name":"Ceip Mestalla","description":"","publisher":{"@id":"https:\/\/www.ceipmestalla.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ceipmestalla.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ceipmestalla.com\/#organization","name":"Ceip Mestalla","url":"https:\/\/www.ceipmestalla.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ceipmestalla.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/cropped-cropped-cropped-cropped-LOGO_Mestalla-1-e1614470494422.png","contentUrl":"https:\/\/www.ceipmestalla.com\/wp-content\/uploads\/2021\/02\/cropped-cropped-cropped-cropped-LOGO_Mestalla-1-e1614470494422.png","width":500,"height":191,"caption":"Ceip Mestalla"},"image":{"@id":"https:\/\/www.ceipmestalla.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/emestalla","https:\/\/www.instagram.com\/colegiomestalla"]}]}},"_links":{"self":[{"href":"https:\/\/www.ceipmestalla.com\/index.php\/wp-json\/wp\/v2\/pages\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ceipmestalla.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ceipmestalla.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ceipmestalla.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ceipmestalla.com\/index.php\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":12,"href":"https:\/\/www.ceipmestalla.com\/index.php\/wp-json\/wp\/v2\/pages\/36\/revisions"}],"predecessor-version":[{"id":2482,"href":"https:\/\/www.ceipmestalla.com\/index.php\/wp-json\/wp\/v2\/pages\/36\/revisions\/2482"}],"wp:attachment":[{"href":"https:\/\/www.ceipmestalla.com\/index.php\/wp-json\/wp\/v2\/media?parent=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}